{"id":155,"count":1,"description":"","link":"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/","name":"The White House","slug":"weisses-haus","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thetravellers.world\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/tag\\\/weisses-haus\\\/#listItem\",\"name\":\"Wei\\u00dfes Haus\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/tag\\\/weisses-haus\\\/#listItem\",\"position\":2,\"name\":\"Wei\\u00dfes Haus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/#collectionpage\",\"url\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/\",\"name\":\"Wei\\u00dfes Haus - theTravellers\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/#organization\",\"name\":\"theTravellers\",\"description\":\"The World in 5 Minutes\",\"url\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/thetravellers.world\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Profilbild_10_theTravellers_Reiseblogger.png\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/#organizationLogo\",\"width\":1500,\"height\":1500,\"caption\":\"Profilbild theTravellers Reisen YouTube\"},\"image\":{\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/155\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/theTravellersYouTube\\\/\",\"https:\\\/\\\/twitter.com\\\/blog_travellers\",\"https:\\\/\\\/www.instagram.com\\\/thetravellers_on_youtube\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/thetravellers\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/\",\"name\":\"theTravellers\",\"description\":\"The World in 5 Minutes\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/thetravellers.world\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wei\u00dfes Haus - theTravellers","description":"","canonical_url":"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/thetravellers.world\/en#listItem","position":1,"name":"Home","item":"https:\/\/thetravellers.world\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/#listItem","name":"Wei\u00dfes Haus"}},{"@type":"ListItem","@id":"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/#listItem","position":2,"name":"Wei\u00dfes Haus","previousItem":{"@type":"ListItem","@id":"https:\/\/thetravellers.world\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/#collectionpage","url":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/","name":"Wei\u00dfes Haus - theTravellers","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/thetravellers.world\/en\/#website"},"breadcrumb":{"@id":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/thetravellers.world\/en\/#organization","name":"theTravellers","description":"The World in 5 Minutes","url":"https:\/\/thetravellers.world\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/thetravellers.world\/wp-content\/uploads\/2020\/02\/Profilbild_10_theTravellers_Reiseblogger.png","@id":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/#organizationLogo","width":1500,"height":1500,"caption":"Profilbild theTravellers Reisen YouTube"},"image":{"@id":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/theTravellersYouTube\/","https:\/\/twitter.com\/blog_travellers","https:\/\/www.instagram.com\/thetravellers_on_youtube\/","https:\/\/www.youtube.com\/c\/thetravellers"]},{"@type":"WebSite","@id":"https:\/\/thetravellers.world\/en\/#website","url":"https:\/\/thetravellers.world\/en\/","name":"theTravellers","description":"The World in 5 Minutes","inLanguage":"en-GB","publisher":{"@id":"https:\/\/thetravellers.world\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/thetravellers.world\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWei\u00dfes Haus\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/thetravellers.world\/en"},{"label":"Wei\u00dfes Haus","link":"https:\/\/thetravellers.world\/en\/tag\/weisses-haus\/"}],"_links":{"self":[{"href":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thetravellers.world\/en\/wp-json\/wp\/v2\/posts?tags=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}